{"id":74,"date":"2026-04-30T11:53:42","date_gmt":"2026-04-30T11:53:42","guid":{"rendered":"https:\/\/prodealsearch.com\/?page_id=74"},"modified":"2026-04-30T11:53:42","modified_gmt":"2026-04-30T11:53:42","slug":"stores","status":"publish","type":"page","link":"https:\/\/prodealsearch.com\/be\/stores\/","title":{"rendered":"Stores"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"all-stores-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stores - ProDealSearch BE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/be\/stores\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stores - ProDealSearch BE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/be\/stores\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch BE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/stores\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/stores\\\/\",\"name\":\"Stores - ProDealSearch BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/#website\"},\"datePublished\":\"2026-04-30T11:53:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/stores\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/be\\\/stores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/stores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/\",\"name\":\"ProDealSearch BE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stores - ProDealSearch BE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/be\/stores\/","og_locale":"en_US","og_type":"article","og_title":"Stores - ProDealSearch BE","og_url":"https:\/\/prodealsearch.com\/be\/stores\/","og_site_name":"ProDealSearch BE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/be\/stores\/","url":"https:\/\/prodealsearch.com\/be\/stores\/","name":"Stores - ProDealSearch BE","isPartOf":{"@id":"https:\/\/prodealsearch.com\/be\/#website"},"datePublished":"2026-04-30T11:53:42+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/be\/stores\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/be\/stores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/be\/stores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/be\/"},{"@type":"ListItem","position":2,"name":"Stores"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/be\/#website","url":"https:\/\/prodealsearch.com\/be\/","name":"ProDealSearch BE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/be\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}