{"id":5,"count":2,"description":"","link":"https:\/\/prodealsearch.com\/de\/category\/technology\/","name":"Technology","slug":"technology","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technology Archives - ProDealSearch DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/de\/category\/technology\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technology Archives - ProDealSearch DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/de\/category\/technology\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch DE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/category\\\/technology\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/category\\\/technology\\\/\",\"name\":\"Technology Archives - ProDealSearch DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/category\\\/technology\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/category\\\/technology\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"name\":\"ProDealSearch DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technology Archives - ProDealSearch DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/de\/category\/technology\/","og_locale":"en_US","og_type":"article","og_title":"Technology Archives - ProDealSearch DE","og_url":"https:\/\/prodealsearch.com\/de\/category\/technology\/","og_site_name":"ProDealSearch DE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/prodealsearch.com\/de\/category\/technology\/","url":"https:\/\/prodealsearch.com\/de\/category\/technology\/","name":"Technology Archives - ProDealSearch DE","isPartOf":{"@id":"https:\/\/prodealsearch.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/prodealsearch.com\/de\/category\/technology\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/de\/category\/technology\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/de\/"},{"@type":"ListItem","position":2,"name":"Technology"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/de\/#website","url":"https:\/\/prodealsearch.com\/de\/","name":"ProDealSearch DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/posts?categories=5"},{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/blog?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}