{"id":458,"date":"2026-07-15T11:39:07","date_gmt":"2026-07-15T11:39:07","guid":{"rendered":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/"},"modified":"2026-07-15T11:39:07","modified_gmt":"2026-07-15T11:39:07","slug":"4-wochen-ruckgaberecht-bei-alza","status":"publish","type":"coupon","link":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/","title":{"rendered":"4 Wochen R\u00fcckgaberecht bei Alza"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"template":"","stores":[42],"class_list":["post-458","coupon","type-coupon","status-publish","hentry","categories-electronics-gadgets","stores-alza-de"],"acf":{"coupon_fields":{"is_verified":true,"popular":false,"logo":null,"discount_percentage":"SALE","discount_description":"4 Wochen R\u00fcckgaberecht bei Alza","discount_details":"","discount_type":"Deal","coupon_type":"sale","discount_link":"https:\/\/api.yadore.com\/v2\/d?url=http%3A%2F%2Falza.de&market=de&projectId=cCYEYVFSa17V&isCouponing=true","coupon_code":"","coupon_store_url":"","expiration_date":"Jul 31, 2026","strapi_id":"","store_order":9,"home_order":99999,"season_order":99999,"category_order":99999,"total_used":3560,"pin_coupon":false,"pinned_image":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch DE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/4-wochen-ruckgaberecht-bei-alza\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/4-wochen-ruckgaberecht-bei-alza\\\/\",\"name\":\"4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\"},\"datePublished\":\"2026-07-15T11:39:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/4-wochen-ruckgaberecht-bei-alza\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/4-wochen-ruckgaberecht-bei-alza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/4-wochen-ruckgaberecht-bei-alza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupons\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4 Wochen R\u00fcckgaberecht bei Alza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"name\":\"ProDealSearch DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/","og_locale":"en_US","og_type":"article","og_title":"4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE","og_url":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/","og_site_name":"ProDealSearch DE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/","url":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/","name":"4 Wochen R\u00fcckgaberecht bei Alza - ProDealSearch DE","isPartOf":{"@id":"https:\/\/prodealsearch.com\/de\/#website"},"datePublished":"2026-07-15T11:39:07+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/de\/coupon\/4-wochen-ruckgaberecht-bei-alza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/de\/"},{"@type":"ListItem","position":2,"name":"Coupons","item":"https:\/\/prodealsearch.com\/de\/coupon\/"},{"@type":"ListItem","position":3,"name":"4 Wochen R\u00fcckgaberecht bei Alza"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/de\/#website","url":"https:\/\/prodealsearch.com\/de\/","name":"ProDealSearch DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon"}],"about":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/types\/coupon"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon\/458\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"stores","embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/stores?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}