{"id":500,"date":"2026-07-15T12:17:19","date_gmt":"2026-07-15T12:17:19","guid":{"rendered":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/"},"modified":"2026-07-15T12:17:19","modified_gmt":"2026-07-15T12:17:19","slug":"13-lampenwelt-gutschein-mit-dem-newsletter","status":"publish","type":"coupon","link":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/","title":{"rendered":"13% Lampenwelt Gutschein mit dem Newsletter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"template":"","stores":[41],"class_list":["post-500","coupon","type-coupon","status-publish","hentry","categories-home-garden","stores-lampenwelt"],"acf":{"coupon_fields":{"is_verified":true,"popular":false,"logo":null,"discount_percentage":"13% OFF","discount_description":"13% Lampenwelt Gutschein mit dem Newsletter","discount_details":"","discount_type":"Deal","coupon_type":"sale","discount_link":"https:\/\/api.yadore.com\/v2\/d?url=https%3A%2F%2Fwww.lampenwelt.de%2F&market=de&projectId=cCYEYVFSa17V&isCouponing=true","coupon_code":"","coupon_store_url":"","expiration_date":"Jul 31, 2026","strapi_id":"","store_order":7,"home_order":99999,"season_order":99999,"category_order":99999,"total_used":2852,"pin_coupon":false,"pinned_image":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch DE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/13-lampenwelt-gutschein-mit-dem-newsletter\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/13-lampenwelt-gutschein-mit-dem-newsletter\\\/\",\"name\":\"13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\"},\"datePublished\":\"2026-07-15T12:17:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/13-lampenwelt-gutschein-mit-dem-newsletter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/13-lampenwelt-gutschein-mit-dem-newsletter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/13-lampenwelt-gutschein-mit-dem-newsletter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupons\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/coupon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"13% Lampenwelt Gutschein mit dem Newsletter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"name\":\"ProDealSearch DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/","og_locale":"en_US","og_type":"article","og_title":"13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE","og_url":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/","og_site_name":"ProDealSearch DE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/","url":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/","name":"13% Lampenwelt Gutschein mit dem Newsletter - ProDealSearch DE","isPartOf":{"@id":"https:\/\/prodealsearch.com\/de\/#website"},"datePublished":"2026-07-15T12:17:19+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/de\/coupon\/13-lampenwelt-gutschein-mit-dem-newsletter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/de\/"},{"@type":"ListItem","position":2,"name":"Coupons","item":"https:\/\/prodealsearch.com\/de\/coupon\/"},{"@type":"ListItem","position":3,"name":"13% Lampenwelt Gutschein mit dem Newsletter"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/de\/#website","url":"https:\/\/prodealsearch.com\/de\/","name":"ProDealSearch DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon\/500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon"}],"about":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/types\/coupon"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/coupon\/500\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/media?parent=500"}],"wp:term":[{"taxonomy":"stores","embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/stores?post=500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}