{"id":107,"date":"2026-05-04T06:37:56","date_gmt":"2026-05-04T06:37:56","guid":{"rendered":"https:\/\/prodealsearch.com\/home\/"},"modified":"2026-05-04T06:37:56","modified_gmt":"2026-05-04T06:37:56","slug":"home","status":"publish","type":"page","link":"https:\/\/prodealsearch.com\/de\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"front-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-107","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - ProDealSearch DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/de\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - ProDealSearch DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch DE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"name\":\"Home - ProDealSearch DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\"},\"datePublished\":\"2026-05-04T06:37:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/\",\"name\":\"ProDealSearch DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - ProDealSearch DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/de\/","og_locale":"en_US","og_type":"article","og_title":"Home - ProDealSearch DE","og_url":"https:\/\/prodealsearch.com\/de\/","og_site_name":"ProDealSearch DE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/de\/","url":"https:\/\/prodealsearch.com\/de\/","name":"Home - ProDealSearch DE","isPartOf":{"@id":"https:\/\/prodealsearch.com\/de\/#website"},"datePublished":"2026-05-04T06:37:56+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/de\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/de\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/de\/#website","url":"https:\/\/prodealsearch.com\/de\/","name":"ProDealSearch DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/pages\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/pages\/107\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/de\/wp-json\/wp\/v2\/media?parent=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}