{"id":472,"date":"2026-07-14T13:07:29","date_gmt":"2026-07-14T13:07:29","guid":{"rendered":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/"},"modified":"2026-07-14T13:07:29","modified_gmt":"2026-07-14T13:07:29","slug":"ensemble-de-literie-50-de-discount","status":"publish","type":"coupon","link":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/","title":{"rendered":"Ensemble de literie : 50% de discount"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"template":"","stores":[48],"class_list":["post-472","coupon","type-coupon","status-publish","hentry","categories-home-garden","stores-emma"],"acf":{"coupon_fields":{"is_verified":true,"popular":false,"logo":null,"discount_percentage":"SALE","discount_description":"Ensemble de literie : 50% de discount","discount_details":"","discount_type":"Deal","coupon_type":"sale","discount_link":"https:\/\/www.emma.fr\/","coupon_code":"","coupon_store_url":"","expiration_date":"Jul 31, 2026","strapi_id":"","store_order":6,"home_order":99999,"season_order":99999,"category_order":99999,"total_used":2842,"pin_coupon":false,"pinned_image":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensemble de literie : 50% de discount - ProDealSearch FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensemble de literie : 50% de discount - ProDealSearch FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch FR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/ensemble-de-literie-50-de-discount\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/ensemble-de-literie-50-de-discount\\\/\",\"name\":\"Ensemble de literie : 50% de discount - ProDealSearch FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-14T13:07:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/ensemble-de-literie-50-de-discount\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/ensemble-de-literie-50-de-discount\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/ensemble-de-literie-50-de-discount\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupons\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/coupon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ensemble de literie : 50% de discount\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/\",\"name\":\"ProDealSearch FR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensemble de literie : 50% de discount - ProDealSearch FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/","og_locale":"en_US","og_type":"article","og_title":"Ensemble de literie : 50% de discount - ProDealSearch FR","og_url":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/","og_site_name":"ProDealSearch FR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/","url":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/","name":"Ensemble de literie : 50% de discount - ProDealSearch FR","isPartOf":{"@id":"https:\/\/prodealsearch.com\/fr\/#website"},"datePublished":"2026-07-14T13:07:29+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/fr\/coupon\/ensemble-de-literie-50-de-discount\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Coupons","item":"https:\/\/prodealsearch.com\/fr\/coupon\/"},{"@type":"ListItem","position":3,"name":"Ensemble de literie : 50% de discount"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/fr\/#website","url":"https:\/\/prodealsearch.com\/fr\/","name":"ProDealSearch FR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/coupon\/472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/coupon"}],"about":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/types\/coupon"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/coupon\/472\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/media?parent=472"}],"wp:term":[{"taxonomy":"stores","embeddable":true,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/stores?post=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}