{"id":76,"date":"2026-04-30T12:06:34","date_gmt":"2026-04-30T12:06:34","guid":{"rendered":"https:\/\/prodealsearch.com\/?page_id=76"},"modified":"2026-04-30T12:06:34","modified_gmt":"2026-04-30T12:06:34","slug":"categories","status":"publish","type":"page","link":"https:\/\/prodealsearch.com\/fr\/categories\/","title":{"rendered":"Categories"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"all-categories-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Categories - ProDealSearch FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodealsearch.com\/fr\/categories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Categories - ProDealSearch FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodealsearch.com\/fr\/categories\/\" \/>\n<meta property=\"og:site_name\" content=\"ProDealSearch FR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/categories\\\/\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/categories\\\/\",\"name\":\"Categories - ProDealSearch FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-04-30T12:06:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/categories\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/categories\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/categories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Categories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/\",\"name\":\"ProDealSearch FR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodealsearch.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Categories - ProDealSearch FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodealsearch.com\/fr\/categories\/","og_locale":"en_US","og_type":"article","og_title":"Categories - ProDealSearch FR","og_url":"https:\/\/prodealsearch.com\/fr\/categories\/","og_site_name":"ProDealSearch FR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodealsearch.com\/fr\/categories\/","url":"https:\/\/prodealsearch.com\/fr\/categories\/","name":"Categories - ProDealSearch FR","isPartOf":{"@id":"https:\/\/prodealsearch.com\/fr\/#website"},"datePublished":"2026-04-30T12:06:34+00:00","breadcrumb":{"@id":"https:\/\/prodealsearch.com\/fr\/categories\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodealsearch.com\/fr\/categories\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodealsearch.com\/fr\/categories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodealsearch.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Categories"}]},{"@type":"WebSite","@id":"https:\/\/prodealsearch.com\/fr\/#website","url":"https:\/\/prodealsearch.com\/fr\/","name":"ProDealSearch FR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodealsearch.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":0,"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"wp:attachment":[{"href":"https:\/\/prodealsearch.com\/fr\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}